{"id":5983,"date":"2024-10-26T22:34:00","date_gmt":"2024-10-26T22:34:00","guid":{"rendered":"http:\/\/www.culturatlaxcala.com.mx\/?p=5983"},"modified":"2024-11-04T22:42:59","modified_gmt":"2024-11-04T22:42:59","slug":"el-carnaval-mas-alla-de-sus-fronteras","status":"publish","type":"post","link":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/2024\/10\/26\/el-carnaval-mas-alla-de-sus-fronteras\/","title":{"rendered":"El Carnaval m\u00e1s All\u00e1 de sus Fronteras"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"764\" height=\"997\" src=\"http:\/\/www.culturatlaxcala.com.mx\/wp-content\/uploads\/2024\/11\/Carnaval_MasAllaFronteras_Oct2024.jpg\" alt=\"\" class=\"wp-image-5984\" srcset=\"https:\/\/www.culturatlaxcala.com.mx\/wp-content\/uploads\/2024\/11\/Carnaval_MasAllaFronteras_Oct2024.jpg 764w, https:\/\/www.culturatlaxcala.com.mx\/wp-content\/uploads\/2024\/11\/Carnaval_MasAllaFronteras_Oct2024-230x300.jpg 230w\" sizes=\"auto, (max-width: 764px) 100vw, 764px\" \/><\/figure>\n\n\n\n<p><strong>Conferencias virtuales<\/strong><br><a href=\"https:\/\/www.facebook.com\/SeCuTlax\/videos\/893436866018338\" target=\"_blank\" rel=\"noreferrer noopener\">1. Conferencia del 04 de octubre de 2024<\/a><br><a href=\"https:\/\/www.facebook.com\/SeCuTlax\/videos\/3815869302027411\" target=\"_blank\" rel=\"noreferrer noopener\">2.- Conferencia del 11 de octubre de 2024<\/a><br><a href=\"https:\/\/www.facebook.com\/SeCuTlax\/videos\/785561843636758\" target=\"_blank\" rel=\"noreferrer noopener\">3.\tConferencia del 18 de octubre de 2024<\/a><br>\n<a href=\"https:\/\/www.facebook.com\/SeCuTlax\/videos\/8751575864906692\" target=\"_blank\" rel=\"noreferrer noopener\">4.\tConferencia del 25 de octubre de 2024<\/a><br><br>\n<a href=\"https:\/\/www.facebook.com\/photo\/?fbid=963292262506522&amp;set=pcb.963292575839824\" target=\"_blank\" rel=\"noreferrer noopener\">conferencia presencial el 15 de octubre de 2024<\/a>\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conferencias virtuales1. Conferencia del 04 de octubre de 20242.- Conferencia del 11 de octubre de 20243. Conferencia del 18 de octubre de 2024 4. Conferencia del 25 de octubre de 2024 conferencia presencial el 15 de octubre de 2024<\/p>\n","protected":false},"author":1,"featured_media":5985,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines"],"_links":{"self":[{"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5983"}],"version-history":[{"count":3,"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5983\/revisions"}],"predecessor-version":[{"id":5989,"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5983\/revisions\/5989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5985"}],"wp:attachment":[{"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.culturatlaxcala.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}